{"id":8007,"date":"2017-09-05T11:42:00","date_gmt":"2017-09-05T11:42:00","guid":{"rendered":"https:\/\/original-militaria.com\/?post_type=product&#038;p=8007"},"modified":"2022-01-31T19:06:35","modified_gmt":"2022-01-31T18:06:35","slug":"wh-reloj-de-bolsillo-dh-de-la-marca-helios","status":"publish","type":"product","link":"https:\/\/original-militaria.com\/en\/producto\/wh-reloj-de-bolsillo-dh-de-la-marca-helios\/","title":{"rendered":"WH\/ Reloj de Bolsillo DH de la Marca &#8220;Helios&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"font-size: medium\"><span style=\"font-family: Verdana\"><strong>ANTECEDENTES:<\/strong> La WH dispon&iacute;a de relojes de bolsillo y pulsera para equipar a Oficiales, suboficiales y tropa, seg&uacute;n las necesidades del servicio. Con la expansi&oacute;n de la guerra se gener&oacute; una gran demanda por parte del OKH (Oberkommando des Heeres), pero las empresas alemanas tales como Hanhart o Junghans no pudieron con la tal demanda. En 1942 se hizo el primer encargo para satisfacer tal demanda a las relojeras Suizas. Estos relojes eran manufacturados seg&uacute;n especificaciones dadas por muchos productores y minoristas alemanes y suizos (Buren, Grana, Zenith, dogma, Helios, Omega, Longines, Minerva, Mimo, Helios etc). Los relojes fueron comprados en parte por los oficiales y tambi&eacute;n vendidos a la tropa del ej&eacute;rcito. Estor relojes se pod&iacute;an comprar tanbien por particulares en las tiendas del ej&eacute;rcito. <\/p>\n<p><strong>DESCRIPCION:<\/strong> Reloj de bolsillo mec&aacute;nico de muy alta calidad con maquinaria antichoque de la relojera <font color=\"#ff0000\">&quot;Helios&quot;<\/font> de 50 mm de di&aacute;metro, tiene la esfera de color negro con segundero a las seis, marcado debajo de las 12,00 con la marca de la relojera y las tres una <span style=\"color: #ff0000\">esv&aacute;stica<\/span> gravada. La tapa trasera estanca es a rosca con tres ranuras conforme a las especificaciones del OKH para los relojes, tiene el n&uacute;mero de serie con <font color=\"#ff0000\">&quot;D..H&quot;<\/font>. La <font color=\"#ff0000\">&quot;D&quot;<\/font> significa reloj de servicio (Dienstuhr) o alem&aacute;n (Deutsches), y la <font color=\"#ff0000\">&quot;H&quot;<\/font> significa ej&eacute;rcito (Heer).&nbsp;Buen funcionamiento, comprobado.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify\"><span style=\"font-size: medium\"><span style=\"font-family: Verdana\"><strong>ANTECEDENTES:<\/strong> La WH dispon&iacute;a de relojes de bolsillo y pulsera para equipar a Oficiales, suboficiales y tropa, seg&uacute;n las necesidades del servicio. Con la expansi&oacute;n de la guerra se gener&oacute; una gran demanda por parte del OKH (Oberkommando des Heeres), pero las empresas alemanas tales como Hanhart o Junghans no pudieron con la tal demanda. En 1942 se hizo el primer encargo para satisfacer tal demanda a las relojeras Suizas. Estos relojes eran manufacturados seg&uacute;n especificaciones dadas por muchos productores y minoristas alemanes y suizos (Buren, Grana, Zenith, dogma, Helios, Omega, Longines, Minerva, Mimo, Helios etc). Los relojes fueron comprados en parte por los oficiales y tambi&eacute;n vendidos a la tropa del ej&eacute;rcito. Estor relojes se pod&iacute;an comprar tanbien por particulares en las tiendas del ej&eacute;rcito. <\/p>\n<p><strong>DESCRIPCION:<\/strong> Reloj de bolsillo mec&aacute;nico de muy alta calidad con maquinaria antichoque de la relojera <font color=\"#ff0000\">&quot;Helios&quot;<\/font> de 50 mm de di&aacute;metro, tiene la esfera de color negro con segundero a las seis, marcado debajo de las 12,00 con la marca de la relojera y las tres una <span style=\"color: #ff0000\">esv&aacute;stica<\/span> gravada. La tapa trasera estanca es a rosca con tres ranuras conforme a las especificaciones del OKH para los relojes, tiene el n&uacute;mero de serie con <font color=\"#ff0000\">&quot;D..H&quot;<\/font>. La <font color=\"#ff0000\">&quot;D&quot;<\/font> significa reloj de servicio (Dienstuhr) o alem&aacute;n (Deutsches), y la <font color=\"#ff0000\">&quot;H&quot;<\/font> significa ej&eacute;rcito (Heer).&nbsp;Buen funcionamiento, comprobado.<\/span><\/span><\/p>\n","protected":false},"featured_media":8008,"template":"","meta":[],"product_brand":[],"product_cat":[224],"product_tag":[],"class_list":{"0":"post-8007","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-archivo-vendidos","7":"sales-flash-overlay","8":"woocommerce-text-align-center","9":"woocommerce-image-align-center","10":"do-quantity-buttons","12":"first","13":"outofstock","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/product\/8007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/media\/8008"}],"wp:attachment":[{"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/media?parent=8007"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/product_brand?post=8007"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/product_cat?post=8007"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/original-militaria.com\/en\/wp-json\/wp\/v2\/product_tag?post=8007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}